{"id":29,"date":"2025-08-15T21:42:20","date_gmt":"2025-08-15T19:42:20","guid":{"rendered":"https:\/\/chezlouise.org\/?p=29"},"modified":"2025-08-15T21:42:20","modified_gmt":"2025-08-15T19:42:20","slug":"la-recette-du-bonheur","status":"publish","type":"post","link":"https:\/\/chezlouise.org\/index.php\/2025\/08\/15\/la-recette-du-bonheur\/","title":{"rendered":"La recette du bonheur"},"content":{"rendered":"\n<p><em>Ou comment \u00e9pater ses invit\u00e9s \u00e0 l&rsquo;ap\u00e9ro.<\/em><\/p>\n\n\n\n<p>Il faut savoir qu\u2019\u00e0 un moment, Chez Louise a failli \u00eatre un blog culinaire. Un cahier de recettes version 2.0. J\u2019en ai finalement achet\u00e9 un en papier. Il est beau\u2026 et si plaisant \u00e0 remplir. C\u2019est une vraie madeleine de Proust, un cahier de recettes.\u00a0<\/p>\n\n\n\n<p>\u00c7a ne m\u2019emp\u00eache pas de vous partager cette recette avec qui j\u2019ai renou\u00e9 cet \u00e9t\u00e9 avec un succ\u00e8s ph\u00e9nom\u00e9nal, soyons honn\u00eate. Il s\u2019agit des <strong>blinis<\/strong>. La recette est simplissime et facile \u00e0 se souvenir, le r\u00e9sultat est bluffant, loin du go\u00fbt chimique des blinis de supermarch\u00e9, bref, pour rester dans le th\u00e8me des derniers articles, c&rsquo;est la recette du bonheur. <\/p>\n\n\n\n<p>Il faut :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>un yaourt \u00e0 la grecque ou fromage blanc ;<\/li>\n\n\n\n<li>un yaourt de farine ;<\/li>\n\n\n\n<li>un oeuf ;<\/li>\n\n\n\n<li>1\/2 sachet de levure ;<\/li>\n\n\n\n<li>du sel.<\/li>\n<\/ul>\n\n\n\n<p>Je fais rarement une seule dose : \u00e7a ne vous fait pas un ap\u00e9ro si vous avez des invit\u00e9s. Je commence par bien m\u00e9langer l\u2019oeuf, j\u2019ajoute le yaourt, puis la farine et la levure en m\u00eame temps et enfin le sel. Le seul truc technique, c\u2019est qu\u2019il faut laisser la pr\u00e9paration une heure au frigo. C\u2019est important. Donc il faut anticiper (c\u2019est souvent ce qui p\u00e8che de mon c\u00f4t\u00e9).&nbsp;<\/p>\n\n\n\n<p>Au bout d\u2019une heure, vous sortez la pr\u00e9paration du frigo, vous prenez votre plus grande po\u00eale, vous faites chauffer une noix de beurre \u00e0 feu moyen et vous faites de petits p\u00e2t\u00e9s avec une cuill\u00e8re \u00e0 soupe. Vous verrez que la p\u00e2te peut \u00eatre tr\u00e8s \u00e9paisse, c\u2019est pour \u00e7a que j\u2019en mets peu. Pour les retourner, j\u2019utilise g\u00e9n\u00e9ralement une spatule en bois et une fourchette.&nbsp;<\/p>\n\n\n\n<p>Il n\u2019y a plus qu\u2019\u00e0 tartiner dessus ce que vous voulez\u2026&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"575\" height=\"301\" src=\"https:\/\/chezlouise.org\/wp-content\/uploads\/2025\/08\/92ad01d3-babf-4c72-8862-d5863a8dc634.jpg\" alt=\"\" class=\"wp-image-30\" srcset=\"https:\/\/chezlouise.org\/wp-content\/uploads\/2025\/08\/92ad01d3-babf-4c72-8862-d5863a8dc634.jpg 575w, https:\/\/chezlouise.org\/wp-content\/uploads\/2025\/08\/92ad01d3-babf-4c72-8862-d5863a8dc634-300x157.jpg 300w\" sizes=\"auto, (max-width: 575px) 100vw, 575px\" \/><\/figure>\n\n\n\n<p>Parce que l\u2019ap\u00e9ro d\u00eenatoire, c\u2019est quand m\u00eame le repas le plus sympa \u00e0 pr\u00e9parer. C\u2019est l\u00e0 qu\u2019on peut \u00eatre cr\u00e9atif, utiliser plein de restes du frigo, proposer plein de saveurs diff\u00e9rentes&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ou comment \u00e9pater ses invit\u00e9s \u00e0 l&rsquo;ap\u00e9ro. Il faut savoir qu\u2019\u00e0 un moment, Chez Louise a failli \u00eatre un blog culinaire. Un cahier de recettes version 2.0. J\u2019en ai finalement achet\u00e9 un en papier. Il est beau\u2026 et si plaisant \u00e0 remplir. C\u2019est une vraie madeleine de Proust, un cahier de recettes.\u00a0 \u00c7a ne m\u2019emp\u00eache [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/chezlouise.org\/index.php\/wp-json\/wp\/v2\/posts\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chezlouise.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chezlouise.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chezlouise.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chezlouise.org\/index.php\/wp-json\/wp\/v2\/comments?post=29"}],"version-history":[{"count":1,"href":"https:\/\/chezlouise.org\/index.php\/wp-json\/wp\/v2\/posts\/29\/revisions"}],"predecessor-version":[{"id":31,"href":"https:\/\/chezlouise.org\/index.php\/wp-json\/wp\/v2\/posts\/29\/revisions\/31"}],"wp:attachment":[{"href":"https:\/\/chezlouise.org\/index.php\/wp-json\/wp\/v2\/media?parent=29"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chezlouise.org\/index.php\/wp-json\/wp\/v2\/categories?post=29"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chezlouise.org\/index.php\/wp-json\/wp\/v2\/tags?post=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}